{"id":990866,"date":"2025-10-17T21:06:37","date_gmt":"2025-10-17T21:06:37","guid":{"rendered":"https:\/\/rdaction.sandbox.8p-design.com\/?page_id=990866"},"modified":"2026-02-18T15:40:33","modified_gmt":"2026-02-18T20:40:33","slug":"cdae-ia","status":"publish","type":"page","link":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/","title":{"rendered":"CDAE-IA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"990866\" class=\"elementor elementor-990866\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50a1d55e elementor-section-content-middle elementor-section-height-min-height elementor-section-items-stretch component-text-image-right elementor-section-boxed elementor-section-height-default\" data-id=\"50a1d55e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b2c90be\" data-id=\"5b2c90be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48a0bd32 elementor-widget elementor-widget-heading\" data-id=\"48a0bd32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des cr\u00e9dits pour le d\u00e9veloppement des affaires \u00e9lectroniques utilisant l\u2019Intelligence Artificielle (CDAE-IA)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f4e59b elementor-widget elementor-widget-text-editor\" data-id=\"1f4e59b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le gouvernement du Qu\u00e9bec a instaur\u00e9 un cr\u00e9dit d\u2019imp\u00f4t pour le d\u00e9veloppement des affaires \u00e9lectroniques int\u00e9grant l\u2019intelligence Artificielle (CDAE-IA). L\u2019objectif est d\u2019encourager le d\u00e9veloppement et l\u2019expansion des technologies de l\u2019information (TI) qui int\u00e8grent des fonctionnalit\u00e9s d\u2019intelligence artificielle (IA) de mani\u00e8re significative.<br \/>Pour avoir droit \u00e0 ces cr\u00e9dits, la soci\u00e9t\u00e9 doit exploiter une entreprise comptant au moins six employ\u00e9s techniques du domaine des TI. Les activit\u00e9s admissibles pour qualifier un employ\u00e9 admissible sont entre autres :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10d9d7d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"10d9d7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Les services-conseils en technologies de l\u2019information<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le d\u00e9veloppement, l\u2019int\u00e9gration et l\u2019entretien de syst\u00e8mes d\u2019information et d\u2019infrastructures technologiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le d\u00e9veloppement de services de s\u00e9curit\u00e9 et d\u2019identification li\u00e9s aux activit\u00e9s d\u2019affaires \u00e9lectroniques.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-0f8fc24 elementor-widget elementor-widget-text-editor\" data-id=\"0f8fc24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour \u00eatre admissible, une activit\u00e9 doit \u00eatre principalement li\u00e9e aux affaires \u00e9lectroniques et se rapporter \u00e0 un mandat, un projet ou un produit qui int\u00e8gre des fonctionnalit\u00e9s d\u2019IA de mani\u00e8re significative.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56966bd7\" data-id=\"56966bd7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:51}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2259cd8d elementor-widget elementor-widget-spacer\" data-id=\"2259cd8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61259e9b elementor-section-content-top elementor-section-height-min-height elementor-section-items-stretch component-opportunity elementor-section-boxed elementor-section-height-default\" data-id=\"61259e9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1654781a column-opportuniy-text\" data-id=\"1654781a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39d314ad card-opportuniy card-opportuniy-text e-flex e-con-boxed e-con e-parent\" data-id=\"39d314ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2814e0 elementor-widget elementor-widget-heading\" data-id=\"5a2814e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'opportunit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-11b8ba9d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"11b8ba9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Toute entreprise du domaine des technologies de l\u2019information (TI) au Qu\u00e9bec peut en profiter. Voyez comment le cr\u00e9dit d\u2019imp\u00f4t CDAE-IA est une opportunit\u00e9 pour vous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-451e8791 card-opportuniy e-flex e-con-boxed e-con e-parent\" data-id=\"451e8791\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7a92f55e e-con-full e-flex e-con e-child\" data-id=\"7a92f55e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ec02367 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5ec02367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20c38584 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"20c38584\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cr\u00e9dit d\u2019imp\u00f4t lucratif\u200b<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-22d01b4e elementor-widget elementor-widget-text-editor\" data-id=\"22d01b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le cr\u00e9dit CDAE-IA est tr\u00e8s lucratif, les cr\u00e9dits d\u2019imp\u00f4t sont de 30% des salaires des employ\u00e9s accept\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6515901b card-opportuniy e-flex e-con-boxed e-con e-parent\" data-id=\"6515901b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2cd7d99f e-con-full e-flex e-con e-child\" data-id=\"2cd7d99f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c4ed02 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1c4ed02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ef48f62 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7ef48f62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Augmente votre rentabilit\u00e9<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-f202e99 elementor-widget elementor-widget-text-editor\" data-id=\"f202e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Combien de ventes devez-vous g\u00e9n\u00e9rer pour faire 100 $ apr\u00e8s imp\u00f4t ?<br \/>Les cr\u00e9dits d\u2019imp\u00f4t c\u2019est de l\u2019argent net apr\u00e8s imp\u00f4t.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b33caef card-opportuniy e-flex e-con-boxed e-con e-parent\" data-id=\"7b33caef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bfee621 e-con-full e-flex e-con e-child\" data-id=\"bfee621\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fdab42e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7fdab42e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c792919 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7c792919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Rester comp\u00e9titif<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-18f45324 elementor-widget elementor-widget-text-editor\" data-id=\"18f45324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vos concurrents exploitent d\u00e9j\u00e0 cette opportunit\u00e9, pourquoi pas vous ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-335d1351 card-opportuniy card-opportuniy-text e-flex e-con-boxed e-con e-parent\" data-id=\"335d1351\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c18d691 elementor-widget elementor-widget-heading\" data-id=\"2c18d691\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les d\u00e9fis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f7c34b2 card-opportuniy e-flex e-con-boxed e-con e-parent\" data-id=\"2f7c34b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7976d38f e-con-full e-flex e-con e-child\" data-id=\"7976d38f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4117ab77 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4117ab77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b7c824f elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7b7c824f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Sp\u00e9cialis\u00e9e en TI<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-2d7836b8 elementor-widget elementor-widget-text-editor\" data-id=\"2d7836b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour se qualifier, il faut \u00e0 la fois d\u00e9montrer que :<\/p><ul><li>75% des revenus de l\u2019entreprise proviennent d\u2019activit\u00e9s en TI int\u00e9grant l\u2019intelligence artificielle de fa\u00e7on significative.<\/li><li>75% des activit\u00e9s des employ\u00e9s r\u00e9clam\u00e9s sont techniques en TI dans es projets int\u00e9grant l\u2019intelligence artificielle de fa\u00e7on significative<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-100f0124 column-opportuniy-stats\" data-id=\"100f0124\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6738e2c6 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"6738e2c6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:80,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4b69affc\" data-id=\"4b69affc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ea878b elementor-widget elementor-widget-counter\" data-id=\"5ea878b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Remboursement possible sur les salaires admissibles pour les PME.<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"30\" data-from-value=\"10\" data-delimiter=\",\">10<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ba49be component-shipping-method elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ba49be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6f2bf7\" data-id=\"c6f2bf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3718d0f shipping-method-content-container e-flex e-con-boxed e-con e-child\" data-id=\"3718d0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f92507a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-template\" data-id=\"f92507a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1002013\" class=\"elementor elementor-1002013\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-b0c1448 e-flex e-con-boxed e-con e-parent\" data-id=\"b0c1448\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a15dfe e-con-full e-flex e-con e-child\" data-id=\"1a15dfe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-983fada e-con-full e-flex e-con e-child\" data-id=\"983fada\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f9ea91 elementor-widget elementor-widget-heading\" data-id=\"0f9ea91\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le service de livraison<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-0bd25b3 elementor-widget elementor-widget-text-editor\" data-id=\"0bd25b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La livraison cl\u00e9-en main couvre tout le processus, de l\u2019identification du potentiel \u00e0 l\u2019encaissement incluant\u00a0:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4edc749 e-con-full e-flex e-con e-child\" data-id=\"4edc749\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd4fdd3 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dd4fdd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Identifier et valider les revenus et les activit\u00e9s \u00e9ligibles<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pr\u00e9parer le dossier (pr\u00e9parer les textes, les co\u00fbts et les formulaires fiscaux)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">D\u00e9fendre la r\u00e9clamation face aux autorit\u00e9s fiscales<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Encaisser  <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Former et supporter vos ressources au CDAE-IA <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-minus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Implanter les meilleures pratiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be8ea5d elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-bottom component-marketing-hero-medium elementor-section-boxed elementor-section-height-default\" data-id=\"be8ea5d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4.79999999999999982236431605997495353221893310546875,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:10,&quot;end&quot;:85}}}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18569fc\" data-id=\"18569fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:66}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af5e3e1 text-shadow-default e-flex e-con-boxed e-con e-parent\" data-id=\"af5e3e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-165aa94 elementor-widget elementor-widget-heading\" data-id=\"165aa94\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parlez \u00e0 un expert<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2357ef3 elementor-widget elementor-widget-heading\" data-id=\"2357ef3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Communiquez avec nous pour une consultation personnalis\u00e9e d\u00e8s aujourd'hui.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-5f62e8d elementor-widget elementor-widget-text-editor\" data-id=\"5f62e8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous voyez d\u2019autres programmes d\u2019int\u00e9r\u00eat? Notre \u00e9quipe est compos\u00e9e d\u2019experts de sortes de tous les domaines technologiques. Nous saurons nous adapter et comprendre ces mesures pour produire vos r\u00e9clamations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-c7664f7 elementor-widget__width-auto vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"c7664f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6OTkxMDg2LCJ0b2dnbGUiOmZhbHNlLCJhbGlnbl93aXRoX3BhcmVudCI6IiJ9\" data-trk-event=\"cta_click\" data-trk-id=\"booking\" data-trk-section=\"speak_to_expert\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir une consultation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6a144b elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"c6a144b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3f92e0 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3f92e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9c557a9\" data-id=\"9c557a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50803e3 elementor-widget elementor-widget-heading\" data-id=\"50803e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Articles relatifs au cr\u00e9dit CDAE-IA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c72ef21\" data-id=\"c72ef21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-7a5f37d elementor-widget__width-auto elementor-mobile-align-left vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"7a5f37d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tous les articles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29713a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29713a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a3f892\" data-id=\"6a3f892\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d9c3e7 elementor-pagination-type-progressbar elementor-arrows-position-inside elementor-widget elementor-widget-loop-carousel\" data-id=\"7d9c3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:7839,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;pagination&quot;:&quot;progressbar&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t<style id=\"loop-7839\">.elementor-7839 .elementor-element.elementor-element-19c84cb{border-style:solid;border-width:1px 1px 1px 1px;border-color:var( --e-global-color-vamtam_accent_7 );margin-top:0px;margin-bottom:0px;padding:0px 0px 0px 0px;}.elementor-7839 .elementor-element.elementor-element-19c84cb a{color:var( --e-global-color-vamtam_accent_1 );}.elementor-7839 .elementor-element.elementor-element-19c84cb a:hover{color:var( --e-global-color-vamtam_accent_2 );}.elementor-7839 .elementor-element.elementor-element-de2c58a > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-block-end:15px;}.elementor-7839 .elementor-element.elementor-element-de2c58a > .elementor-element-populated{padding-block-start:20px;padding-inline-start:30px;padding-block-end:50px;padding-inline-end:30px;}.elementor-7839 .elementor-element.elementor-element-f420d3f img{width:100%;max-width:100%;height:215px;object-fit:cover;object-position:center center;}.elementor-7839 .elementor-element.elementor-element-f420d3f:hover img{filter:brightness( 100% ) contrast( 100% ) saturate( 100% ) blur( 0px ) hue-rotate( 0deg );}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button .elementor-button-content-wrapper{justify-content:start;}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button{font-family:var( --e-global-typography-vamtam_h5-font-family ), Sans-serif;font-size:var( --e-global-typography-vamtam_h5-font-size );font-weight:var( --e-global-typography-vamtam_h5-font-weight );text-transform:var( --e-global-typography-vamtam_h5-text-transform );font-style:var( --e-global-typography-vamtam_h5-font-style );line-height:var( --e-global-typography-vamtam_h5-line-height );letter-spacing:var( --e-global-typography-vamtam_h5-letter-spacing );fill:var( --e-global-color-vamtam_accent_6 );color:var( --e-global-color-vamtam_accent_6 );border-style:none;padding:0px 0px 0px 0px;}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button:hover, .elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button:focus{color:var( --e-global-color-vamtam_accent_6 );background-color:#FFFFFF00;}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button:hover svg, .elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button:focus svg{fill:var( --e-global-color-vamtam_accent_6 );}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button-text{--vamtam-underline-bg-color:var( --e-global-color-vamtam_accent_2 );}.elementor-7839 .elementor-element.elementor-element-1f17bbe > .elementor-widget-container{margin:8px 0px 8px 0px;}@media(max-width:1024px){.elementor-7839 .elementor-element.elementor-element-de2c58a > .elementor-element-populated{padding-block-start:20px;padding-inline-start:20px;padding-block-end:40px;padding-inline-end:20px;}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button{font-size:var( --e-global-typography-vamtam_h5-font-size );line-height:var( --e-global-typography-vamtam_h5-line-height );letter-spacing:var( --e-global-typography-vamtam_h5-letter-spacing );}}@media(max-width:767px){.elementor-7839 .elementor-element.elementor-element-de2c58a > .elementor-element-populated{padding-block-start:20px;padding-inline-start:20px;padding-block-end:30px;padding-inline-end:20px;}.elementor-7839 .elementor-element.elementor-element-1f17bbe .elementor-button{font-size:var( --e-global-typography-vamtam_h5-font-size );line-height:var( --e-global-typography-vamtam_h5-line-height );letter-spacing:var( --e-global-typography-vamtam_h5-letter-spacing );}}\/* Start custom CSS for shortcode, class: .elementor-element-1b7fc09 *\/.elementor-7839 .elementor-element.elementor-element-1b7fc09 .article-categories-custom{\n    font-size: 12px; \n    font-weight: 700; \n    line-height: 1.2em;\n}\/* End custom CSS *\/\n\/* Start custom CSS for theme-post-featured-image, class: .elementor-element-f420d3f *\/.elementor-7839 .elementor-element.elementor-element-f420d3f a{\n    width: 100%;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"7839\" class=\"elementor elementor-7839 swiper-slide e-loop-item e-loop-item-5654 post-5654 post type-post status-publish format-standard has-post-thumbnail hentry category-cdae-ia category-menu-blog\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19c84cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"19c84cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de2c58a\" data-id=\"de2c58a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7fc09 elementor-widget elementor-widget-shortcode\" data-id=\"1b7fc09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"article-categories-custom\"><a href=\"https:\/\/rdactionconsultant.com\/fr\/categorie\/cdae-ia\/\">CDAE-IA<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f420d3f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"f420d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/attestations-cdae-dinvestissement-quebec\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"329\" src=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Shopping-ecommerce-1920-scaled-1-768x329.jpg\" class=\"attachment-medium_large size-medium_large wp-image-16996\" alt=\"Commerce \u00e9lectronique\" srcset=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Shopping-ecommerce-1920-scaled-1-768x329.jpg 768w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Shopping-ecommerce-1920-scaled-1-300x128.jpg 300w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Shopping-ecommerce-1920-scaled-1.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f17bbe elementor-align-justify vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"1f17bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/attestations-cdae-dinvestissement-quebec\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Attestations CDAE d\u2019Investissement Qu\u00e9bec<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635e7e elementor-widget elementor-widget-shortcode\" data-id=\"1635e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">Quelles sont les attestations CDAE d\u2019Investissement Qu\u00e9bec? Comment les obtenir ?<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"7839\" class=\"elementor elementor-7839 swiper-slide e-loop-item e-loop-item-5458 post-5458 post type-post status-publish format-standard has-post-thumbnail hentry category-cdae-ia category-menu-blog\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19c84cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"19c84cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de2c58a\" data-id=\"de2c58a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7fc09 elementor-widget elementor-widget-shortcode\" data-id=\"1b7fc09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"article-categories-custom\"><a href=\"https:\/\/rdactionconsultant.com\/fr\/categorie\/cdae-ia\/\">CDAE-IA<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f420d3f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"f420d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/pari-ou-rsde\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"394\" src=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Bizarre-1920-768x394.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5461\" alt=\"RSDE ou PARI ?\" srcset=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Bizarre-1920-768x394.jpg 768w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Bizarre-1920-300x154.jpg 300w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Bizarre-1920.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f17bbe elementor-align-justify vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"1f17bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/pari-ou-rsde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PARI ou RS&#038;DE?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635e7e elementor-widget elementor-widget-shortcode\" data-id=\"1635e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">PARI ou RS&amp;DE? Le programme PARI offre un support professionnel et des versements trimestriels. Le programme RS&amp;DE est plus g\u00e9n\u00e9reux mais il faut attendre d&#039;\u00eatre cotis\u00e9<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"7839\" class=\"elementor elementor-7839 swiper-slide e-loop-item e-loop-item-5477 post-5477 post type-post status-publish format-standard has-post-thumbnail hentry category-cdae-ia\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19c84cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"19c84cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de2c58a\" data-id=\"de2c58a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7fc09 elementor-widget elementor-widget-shortcode\" data-id=\"1b7fc09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"article-categories-custom\"><a href=\"https:\/\/rdactionconsultant.com\/fr\/categorie\/cdae-ia\/\">CDAE-IA<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f420d3f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"f420d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/cdae-ou-rsde\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"734\" src=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/bird-3696862_1920-768x734.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5478\" alt=\"RSDE ou CDAE ?\" srcset=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/bird-3696862_1920-768x734.jpg 768w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/bird-3696862_1920-300x287.jpg 300w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/bird-3696862_1920.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f17bbe elementor-align-justify vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"1f17bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/cdae-ou-rsde\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CDAE ou RS&#038;DE?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635e7e elementor-widget elementor-widget-shortcode\" data-id=\"1635e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">CDAE ou RS&amp;DE ? L\u2019admissibilit\u00e9 au cr\u00e9dit CDAE est moins contraignante, plus pr\u00e9dictible et plus facile \u00e0 maintenir pour plusieurs ann\u00e9es que la RS&amp;DE<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"7839\" class=\"elementor elementor-7839 swiper-slide e-loop-item e-loop-item-5600 post-5600 post type-post status-publish format-standard has-post-thumbnail hentry category-cdae-ia\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19c84cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"19c84cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de2c58a\" data-id=\"de2c58a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7fc09 elementor-widget elementor-widget-shortcode\" data-id=\"1b7fc09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"article-categories-custom\"><a href=\"https:\/\/rdactionconsultant.com\/fr\/categorie\/cdae-ia\/\">CDAE-IA<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f420d3f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"f420d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/activites-admissibles-au-cdae\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"502\" src=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-11-1-scaled-1-768x502.jpg\" class=\"attachment-medium_large size-medium_large wp-image-14992\" alt=\"Activit\u00e9s \u00e9ligibles CDAE\" srcset=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-11-1-scaled-1-768x502.jpg 768w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-11-1-scaled-1-300x196.jpg 300w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-11-1-scaled-1.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f17bbe elementor-align-justify vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"1f17bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/activites-admissibles-au-cdae\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Activit\u00e9s admissibles au CDAE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635e7e elementor-widget elementor-widget-shortcode\" data-id=\"1635e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">Activit\u00e9s admissibles CDAE : obtenez chaque ann\u00e9e des cr\u00e9dits d\u2019imp\u00f4t CDAE de 30% des salaires vers\u00e9s \u00e0 vos ressources TI pour accro\u00eetre votre comp\u00e9titivit\u00e9<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"7839\" class=\"elementor elementor-7839 swiper-slide e-loop-item e-loop-item-5525 post-5525 post type-post status-publish format-standard has-post-thumbnail hentry category-cdae-ia\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19c84cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"19c84cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de2c58a\" data-id=\"de2c58a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7fc09 elementor-widget elementor-widget-shortcode\" data-id=\"1b7fc09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"article-categories-custom\"><a href=\"https:\/\/rdactionconsultant.com\/fr\/categorie\/cdae-ia\/\">CDAE-IA<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f420d3f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"f420d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/cdae-pour-la-croissance-en-ti\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"497\" src=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-2-1920-768x497.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5527\" alt=\"CDAE : D\u00e9veloppement, consultation en indormatique\" srcset=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-2-1920-768x497.jpg 768w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-2-1920-300x194.jpg 300w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/Team-2-1920.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f17bbe elementor-align-justify vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"1f17bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/cdae-pour-la-croissance-en-ti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CDAE\u00a0: Pour la croissance en TI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635e7e elementor-widget elementor-widget-shortcode\" data-id=\"1635e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">CDAE\u00a0: Pour la croissance en TI. Cr\u00e9dit d&#039;imp\u00f4t de 30% des salaires admissibles pour les entreprises en TI de 6 employ\u00e9s et plus<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"7839\" class=\"elementor elementor-7839 swiper-slide e-loop-item e-loop-item-5611 post-5611 post type-post status-publish format-standard has-post-thumbnail hentry category-cdae-ia\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19c84cb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"19c84cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de2c58a\" data-id=\"de2c58a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b7fc09 elementor-widget elementor-widget-shortcode\" data-id=\"1b7fc09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"article-categories-custom\"><a href=\"https:\/\/rdactionconsultant.com\/fr\/categorie\/cdae-ia\/\">CDAE-IA<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f420d3f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"f420d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/combien-de-credits-cdae\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"584\" src=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/money-1280-2-768x584.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5612\" alt=\"Combien de cr\u00e9dits CDAE\" srcset=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/money-1280-2-768x584.jpg 768w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/money-1280-2-300x228.jpg 300w, https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2019\/09\/money-1280-2.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-1f17bbe elementor-align-justify vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"1f17bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/combien-de-credits-cdae\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Combien de cr\u00e9dits CDAE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635e7e elementor-widget elementor-widget-shortcode\" data-id=\"1635e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">Combien de cr\u00e9dits CDAE : u maximum de 20,000$ remboursable et 5,000$ non remboursable par ann\u00e9e<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Des cr\u00e9dits pour le d\u00e9veloppement des affaires \u00e9lectroniques utilisant l\u2019Intelligence Artificielle (CDAE-IA) Le gouvernement du Qu\u00e9bec a instaur\u00e9 un cr\u00e9dit d\u2019imp\u00f4t pour le d\u00e9veloppement des affaires \u00e9lectroniques int\u00e9grant l\u2019intelligence Artificielle (CDAE-IA). L\u2019objectif est d\u2019encourager le d\u00e9veloppement et l\u2019expansion des technologies de l\u2019information (TI) qui int\u00e8grent des fonctionnalit\u00e9s d\u2019intelligence artificielle (IA) de mani\u00e8re significative.Pour avoir droit&#8230;<\/p>\n","protected":false},"author":8,"featured_media":1001830,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-990866","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cr\u00e9dit d&#039;Imp\u00f4t CDAE et Intelligence Artificielle (IA) | R&amp;D Action<\/title>\n<meta name=\"description\" content=\"Obtenez jusqu&#039;\u00e0 30% de cr\u00e9dit d&#039;imp\u00f4t sur les salaires TI avec le CDAE. Expertise compl\u00e8te pour les entreprises en TI et IA au Qu\u00e9bec.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9dit d&#039;Imp\u00f4t CDAE et Intelligence Artificielle (IA) | R&amp;D Action\" \/>\n<meta property=\"og:description\" content=\"Obtenez jusqu&#039;\u00e0 30% de cr\u00e9dit d&#039;imp\u00f4t sur les salaires TI avec le CDAE. Expertise compl\u00e8te pour les entreprises en TI et IA au Qu\u00e9bec.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/\" \/>\n<meta property=\"og:site_name\" content=\"R&amp;D Action\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RD-Action-106172664280275\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T20:40:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2025\/12\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MichelRheault\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/\",\"name\":\"Cr\u00e9dit d'Imp\u00f4t CDAE et Intelligence Artificielle (IA) | R&D Action\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg\",\"datePublished\":\"2025-10-17T21:06:37+00:00\",\"dateModified\":\"2026-02-18T20:40:33+00:00\",\"description\":\"Obtenez jusqu'\u00e0 30% de cr\u00e9dit d'imp\u00f4t sur les salaires TI avec le CDAE. Expertise compl\u00e8te pour les entreprises en TI et IA au Qu\u00e9bec.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg\",\"contentUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg\",\"width\":2048,\"height\":2560,\"caption\":\"une main tendue vers une main de robot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/cdae-ia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogue\",\"item\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CDAE-IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\",\"name\":\"R&D Action\",\"description\":\"R&amp;D Action Consultant est votre partenaire privil\u00e9gi\u00e9 pour votre cr\u00e9dit d\u2019imp\u00f4t recherche et votre subvention d\u2019entreprise au Qu\u00e9bec. Nos services s\u2019adaptent \u00e0 vos besoins.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\",\"name\":\"R&D Action\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/rd-action-white-logo.png\",\"contentUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/rd-action-white-logo.png\",\"width\":640,\"height\":172,\"caption\":\"R&D Action\"},\"image\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RD-Action-106172664280275\\\/\",\"https:\\\/\\\/x.com\\\/MichelRheault\",\"https:\\\/\\\/ca.linkedin.com\\\/in\\\/michelrheault-rdaction\",\"https:\\\/\\\/www.instagram.com\\\/r_daction\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cr\u00e9dit d'Imp\u00f4t CDAE et Intelligence Artificielle (IA) | R&D Action","description":"Obtenez jusqu'\u00e0 30% de cr\u00e9dit d'imp\u00f4t sur les salaires TI avec le CDAE. Expertise compl\u00e8te pour les entreprises en TI et IA au Qu\u00e9bec.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/","og_locale":"fr_FR","og_type":"article","og_title":"Cr\u00e9dit d'Imp\u00f4t CDAE et Intelligence Artificielle (IA) | R&D Action","og_description":"Obtenez jusqu'\u00e0 30% de cr\u00e9dit d'imp\u00f4t sur les salaires TI avec le CDAE. Expertise compl\u00e8te pour les entreprises en TI et IA au Qu\u00e9bec.","og_url":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/","og_site_name":"R&amp;D Action","article_publisher":"https:\/\/www.facebook.com\/RD-Action-106172664280275\/","article_modified_time":"2026-02-18T20:40:33+00:00","og_image":[{"width":2048,"height":2560,"url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2025\/12\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MichelRheault","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/","url":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/","name":"Cr\u00e9dit d'Imp\u00f4t CDAE et Intelligence Artificielle (IA) | R&D Action","isPartOf":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/#primaryimage"},"image":{"@id":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2025\/12\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg","datePublished":"2025-10-17T21:06:37+00:00","dateModified":"2026-02-18T20:40:33+00:00","description":"Obtenez jusqu'\u00e0 30% de cr\u00e9dit d'imp\u00f4t sur les salaires TI avec le CDAE. Expertise compl\u00e8te pour les entreprises en TI et IA au Qu\u00e9bec.","breadcrumb":{"@id":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/#primaryimage","url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2025\/12\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg","contentUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2025\/12\/cdae-ia-des-credits-pour-le-developpement-des-affaires-electroniques-utilisant-lintelligence-artificielle-rd-action-banner-scaled-e1764884361656.jpg","width":2048,"height":2560,"caption":"une main tendue vers une main de robot"},{"@type":"BreadcrumbList","@id":"https:\/\/rdactionconsultant.com\/fr\/cdae-ia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rdactionconsultant.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blogue","item":"https:\/\/rdactionconsultant.com\/fr\/blogue\/"},{"@type":"ListItem","position":3,"name":"CDAE-IA"}]},{"@type":"WebSite","@id":"https:\/\/rdactionconsultant.com\/fr\/#website","url":"https:\/\/rdactionconsultant.com\/fr\/","name":"R&D Action","description":"R&amp;D Action Consultant est votre partenaire privil\u00e9gi\u00e9 pour votre cr\u00e9dit d\u2019imp\u00f4t recherche et votre subvention d\u2019entreprise au Qu\u00e9bec. Nos services s\u2019adaptent \u00e0 vos besoins.","publisher":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdactionconsultant.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rdactionconsultant.com\/fr\/#organization","name":"R&D Action","url":"https:\/\/rdactionconsultant.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2023\/06\/rd-action-white-logo.png","contentUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2023\/06\/rd-action-white-logo.png","width":640,"height":172,"caption":"R&D Action"},"image":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RD-Action-106172664280275\/","https:\/\/x.com\/MichelRheault","https:\/\/ca.linkedin.com\/in\/michelrheault-rdaction","https:\/\/www.instagram.com\/r_daction\/"]}]}},"_links":{"self":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages\/990866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/comments?post=990866"}],"version-history":[{"count":158,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages\/990866\/revisions"}],"predecessor-version":[{"id":1003539,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages\/990866\/revisions\/1003539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/media\/1001830"}],"wp:attachment":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/media?parent=990866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}