{"id":999113,"date":"2025-11-17T17:26:40","date_gmt":"2025-11-17T17:26:40","guid":{"rendered":"https:\/\/rdaction.sandbox.8p-design.com\/?page_id=999113"},"modified":"2025-12-16T15:28:26","modified_gmt":"2025-12-16T15:28:26","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"999113\" class=\"elementor elementor-999113\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2431298 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"2431298\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db8bdb3\" data-id=\"db8bdb3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-819decf elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"819decf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-528c121\" data-id=\"528c121\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c1a7202 elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"c1a7202\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bee4845\" data-id=\"bee4845\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d46bfc elementor-align-start elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9d46bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-brand-symbol\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R&amp;D Action<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e60fc1 elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default\" data-id=\"2e60fc1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9120664\" data-id=\"9120664\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a04958 elementor-widget elementor-widget-heading\" data-id=\"7a04958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b5ab8c7\" data-id=\"b5ab8c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09ad2e9 elementor-hidden-mobile\" data-id=\"09ad2e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d72d79a elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"d72d79a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5595e20\" data-id=\"5595e20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69582bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69582bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f555b1\" data-id=\"2f555b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b677a71 elementor-widget elementor-widget-html\" data-id=\"b677a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Start CookieYes cookie policy -->\n<h2 class=\"cookie-policy-h1\">Politique de cookies<\/h2>\n<div class=\"cookie-policy-date-container\">\n  <p>Date d'entr\u00e9e en vigueur: 16 D\u00e9cembre 2025<br \/>\nDerni\u00e8re mise \u00e0 jour: 16 D\u00e9cembre 2025<\/p>\n<\/div><h3>Que sont les cookies?<\/h3>\n<div class=\"cookie-policy-p\">\n  <p>Cette politique explique ce que sont les cookies, comment nous les utilisons, quels types de cookies nous utilisons (c'est-\u00e0-dire les informations que nous collectons \u00e0 l'aide des cookies et la mani\u00e8re dont ces informations sont utilis\u00e9es), ainsi que la mani\u00e8re de g\u00e9rer vos param\u00e8tres de cookies.<\/p>\n  <p>Les cookies sont de petits fichiers texte servant \u00e0 stocker de petites informations. Ils sont enregistr\u00e9s sur votre appareil lorsque vous chargez un site Web dans votre navigateur. Les cookies nous aident \u00e0 garantir le bon fonctionnement du site Web, \u00e0 renforcer la s\u00e9curit\u00e9, \u00e0 am\u00e9liorer l'exp\u00e9rience utilisateur et \u00e0 analyser les performances afin d'identifier les \u00e9l\u00e9ments fonctionnels et les domaines o\u00f9 des am\u00e9liorations sont n\u00e9cessaires.<\/p>\n<\/div><h3>Comment utilisons-nous les cookies?<\/h3>\n<div class=\"cookie-policy-p\">\n  <p>Comme la plupart des services en ligne, notre site Web utilise \u00e0 la fois des cookies de premi\u00e8re partie et des cookies tiers \u00e0 diverses fins. Les cookies de premi\u00e8re partie sont principalement n\u00e9cessaires au bon fonctionnement du site Web et ne collectent aucune donn\u00e9e permettant d'identifier personnellement l'utilisateur.<\/p>\n  <p>Les cookies de tiers utilis\u00e9s sur notre site Web nous aident principalement \u00e0 comprendre les performances du site, \u00e0 suivre votre mani\u00e8re d'interagir avec lui, \u00e0 maintenir la s\u00e9curit\u00e9 de nos services, \u00e0 diffuser des publicit\u00e9s pertinentes et \u00e0 am\u00e9liorer votre exp\u00e9rience utilisateur globale, tout en optimisant la vitesse de vos futures interactions avec notre site.<\/p>\n<\/div><h3>Types de cookies que nous utilisons<\/h3>\n<div class=\"cky-audit-table-element\"><\/div>\n<h3 style=\"margin-bottom: 20px\">G\u00e9rer les pr\u00e9f\u00e9rences de cookies<\/h3><a class=\"cky-banner-element\">Pr\u00e9f\u00e9rences de consentement<\/a><br \/>\n<div>\n  <p>Vous pouvez modifier vos param\u00e8tres de cookies \u00e0 tout moment en cliquant sur le bouton \u00ab Pr\u00e9f\u00e9rences de consentement \u00bb ci-dessus. Cela vous permettra de revenir sur la banni\u00e8re de consentement aux cookies, de mettre \u00e0 jour vos pr\u00e9f\u00e9rences ou de retirer imm\u00e9diatement votre consentement. <\/p>\n  <p>De plus, diff\u00e9rents navigateurs proposent diff\u00e9rentes m\u00e9thodes pour bloquer et supprimer les cookies utilis\u00e9s par les sites Web. Vous pouvez ajuster les param\u00e8tres de votre navigateur pour bloquer ou supprimer les cookies. Vous trouverez ci-dessous des liens vers des documents d'assistance sur la fa\u00e7on de g\u00e9rer et de supprimer les cookies sur les principaux navigateurs Web.<\/p>\n  <p>Chrome: <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/support.google.com\/accounts\/answer\/32050\">https:\/\/support.google.com\/accounts\/answer\/32050<\/a><\/p>\n  <p>Safari: <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/support.apple.com\/en-in\/guide\/safari\/sfri11471\/mac\">https:\/\/support.apple.com\/en-in\/guide\/safari\/sfri11471\/mac<\/a><\/p>\n  <p>Firefox: <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/support.mozilla.org\/en-US\/kb\/clear-cookies-and-site-data-firefox?redirectslug=delete-cookies-remove-info-websites-stored&redirectlocale=en-US\">https:\/\/support.mozilla.org\/en-US\/kb\/clear-cookies-and-site-data-firefox?redirectslug=delete-cookies-remove-info-websites-stored&redirectlocale=en-US<\/a><\/p>\n  <p>Internet Explorer: <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/support.microsoft.com\/en-us\/topic\/how-to-delete-cookie-files-in-internet-explorer-bca9446f-d873-78de-77ba-d42645fa52fc\">https:\/\/support.microsoft.com\/en-us\/topic\/how-to-delete-cookie-files-in-internet-explorer-bca9446f-d873-78de-77ba-d42645fa52fc<\/a><\/p>\n  <p>Si vous utilisez un autre navigateur, veuillez vous r\u00e9f\u00e9rer \u00e0 sa documentation officielle.<\/p>\n<\/div>\n<!-- End CookieYes cookie policy -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-6b9dadc elementor-widget elementor-widget-text-editor\" data-id=\"6b9dadc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Personne \u00e0 contacter:<\/strong> Michel Rheault, <a href=\"tel:5148834825\">(514) 883-4825<\/a>, <a href=\"mailto:info@rdactionconsultant.com\">info@rdactionconsultant.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 Politique de cookies Date d&rsquo;entr\u00e9e en vigueur: 16 D\u00e9cembre 2025 Derni\u00e8re mise \u00e0 jour: 16 D\u00e9cembre 2025 Que sont les cookies? Cette politique explique ce que sont les cookies, comment nous les utilisons, quels types de cookies nous utilisons (c&rsquo;est-\u00e0-dire les informations que nous collectons \u00e0 l&rsquo;aide des cookies et la mani\u00e8re&#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-999113","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de Confidentialit\u00e9 | R&amp;D Action<\/title>\n<meta name=\"description\" content=\"Notre engagement envers la protection de vos renseignements personnels et la confidentialit\u00e9 de vos donn\u00e9es d&#039;entreprise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de Confidentialit\u00e9 | R&amp;D Action\" \/>\n<meta property=\"og:description\" content=\"Notre engagement envers la protection de vos renseignements personnels et la confidentialit\u00e9 de vos donn\u00e9es d&#039;entreprise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"R&amp;D Action\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RD-Action-106172664280275\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T15:28:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MichelRheault\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de Confidentialit\u00e9 | R&D Action\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-11-17T17:26:40+00:00\",\"dateModified\":\"2025-12-16T15:28:26+00:00\",\"description\":\"Notre engagement envers la protection de vos renseignements personnels et la confidentialit\u00e9 de vos donn\u00e9es d'entreprise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\",\"name\":\"R&D Action\",\"description\":\"R&amp;D Action Consultant est votre partenaire privil\u00e9gi\u00e9 pour votre cr\u00e9dit d\u2019imp\u00f4t recherche et votre subvention d\u2019entreprise au Qu\u00e9bec. Nos services s\u2019adaptent \u00e0 vos besoins.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\",\"name\":\"R&D Action\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/rd-action-white-logo.png\",\"contentUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/rd-action-white-logo.png\",\"width\":640,\"height\":172,\"caption\":\"R&D Action\"},\"image\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RD-Action-106172664280275\\\/\",\"https:\\\/\\\/x.com\\\/MichelRheault\",\"https:\\\/\\\/ca.linkedin.com\\\/in\\\/michelrheault-rdaction\",\"https:\\\/\\\/www.instagram.com\\\/r_daction\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de Confidentialit\u00e9 | R&D Action","description":"Notre engagement envers la protection de vos renseignements personnels et la confidentialit\u00e9 de vos donn\u00e9es d'entreprise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de Confidentialit\u00e9 | R&D Action","og_description":"Notre engagement envers la protection de vos renseignements personnels et la confidentialit\u00e9 de vos donn\u00e9es d'entreprise.","og_url":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/","og_site_name":"R&amp;D Action","article_publisher":"https:\/\/www.facebook.com\/RD-Action-106172664280275\/","article_modified_time":"2025-12-16T15:28:26+00:00","twitter_card":"summary_large_image","twitter_site":"@MichelRheault","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/","url":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/","name":"Politique de Confidentialit\u00e9 | R&D Action","isPartOf":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#website"},"datePublished":"2025-11-17T17:26:40+00:00","dateModified":"2025-12-16T15:28:26+00:00","description":"Notre engagement envers la protection de vos renseignements personnels et la confidentialit\u00e9 de vos donn\u00e9es d'entreprise.","breadcrumb":{"@id":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rdactionconsultant.com\/fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rdactionconsultant.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/rdactionconsultant.com\/fr\/#website","url":"https:\/\/rdactionconsultant.com\/fr\/","name":"R&D Action","description":"R&amp;D Action Consultant est votre partenaire privil\u00e9gi\u00e9 pour votre cr\u00e9dit d\u2019imp\u00f4t recherche et votre subvention d\u2019entreprise au Qu\u00e9bec. Nos services s\u2019adaptent \u00e0 vos besoins.","publisher":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdactionconsultant.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rdactionconsultant.com\/fr\/#organization","name":"R&D Action","url":"https:\/\/rdactionconsultant.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2023\/06\/rd-action-white-logo.png","contentUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2023\/06\/rd-action-white-logo.png","width":640,"height":172,"caption":"R&D Action"},"image":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RD-Action-106172664280275\/","https:\/\/x.com\/MichelRheault","https:\/\/ca.linkedin.com\/in\/michelrheault-rdaction","https:\/\/www.instagram.com\/r_daction\/"]}]}},"_links":{"self":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages\/999113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/comments?post=999113"}],"version-history":[{"count":28,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages\/999113\/revisions"}],"predecessor-version":[{"id":1003236,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/pages\/999113\/revisions\/1003236"}],"wp:attachment":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/media?parent=999113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}