{"id":1599,"date":"2016-09-27T14:18:18","date_gmt":"2016-09-27T19:18:18","guid":{"rendered":"http:\/\/rdactionconsultant.com\/?p=1599"},"modified":"2025-11-27T18:29:29","modified_gmt":"2025-11-27T18:29:29","slug":"comment-rediger-votre-description","status":"publish","type":"post","link":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/","title":{"rendered":"Comment r\u00e9diger votre description RS&#038;DE"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\nPour r\u00e9clamer des cr\u00e9dits RS&amp;DE vous devez remplir le <strong><a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/formulaires-publications\/formulaires\/t661.html\" target=\"_blank\" rel=\"noopener noreferrer\">formulaire T661<\/a>.<\/strong> L\u2019ARC fournit plusieurs informations pour faciliter la pr\u00e9paration des dossiers de r\u00e9clamation et pr\u00e9parer ce formulaire\u00a0:<\/p>\n<ul>\n<li>Le <strong><a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/formulaires-publications\/publications\/t4088.html\" target=\"_blank\" rel=\"noopener noreferrer\">guide T4088<\/a><\/strong> explique comment remplir ce formulaire ligne par ligne.<\/li>\n<li>La <strong><a href=\"https:\/\/www.cra-arc.gc.ca\/txcrdt\/sred-rsde\/clmng\/lgbltywrkfrsrdnvstmnttxcrdts-fra.html\" target=\"_blank\" rel=\"noopener noreferrer\">politique sur l&rsquo;admissibilit\u00e9 des travaux \u00e0 la RS&amp;DE<\/a><\/strong> propose une m\u00e9thodologie pour d\u00e9terminer s\u2019il y a de la RS&amp;DE et comment identifier quels travaux constituent de la RS&amp;DE.<\/li>\n<li>Plusieurs autres documents sont disponibles sur le <strong><a href=\"https:\/\/www.cra-arc.gc.ca\/txcrdt\/sred-rsde\/menu-fra.html\" target=\"_blank\" rel=\"noopener noreferrer\">site de l\u2019ARC<\/a>.<\/strong><\/li>\n<\/ul>\n<h2>1- Trop de d\u00e9tails tuent la clart\u00e9<\/h2>\n<p>Malgr\u00e9 la volont\u00e9 de l\u2019Agence, plus on lit ces documents et plus on devient confus. Pourquoi cette confusion ? Deux raisons s\u2019imposent\u00a0selon nous :<\/p>\n<ul>\n<li>Ces documents sont tous tr\u00e8s acad\u00e9miques. Ils sont destin\u00e9s aux scientifiques de l\u2019ARC et aux expert pr\u00e9parateurs qui livrent ce type de dossiers \u00e0 temps plein. Ces documents ont un c\u00f4t\u00e9 l\u00e9gal, ils pr\u00e9sentent plusieurs d\u00e9finitions importantes, apportent des pr\u00e9cisions subtiles, mais s\u2019en tiennent \u00e0 d\u00e9crire formellement ce qui est attendu, le QUOI.<\/li>\n<li>Le contribuable typique a les pieds ancr\u00e9s dans la r\u00e9alit\u00e9. Il a une base scientifique, c\u2019est un ing\u00e9nieur, un technicien ou un informaticien. Mais la r\u00e9alit\u00e9 des entreprises reste la m\u00eame\u00a0: une \u00e9quipe de production et de d\u00e9veloppement subit des contraintes de livraison, techniques et commerciales. Le r\u00e9dacteur a besoin d\u2019\u00eatre guid\u00e9, qu\u2019on lui fournisse une recette expliquant COMMENT produire le texte.<\/li>\n<\/ul>\n<p>Les exigences de l\u2019ARC ont \u00e9volu\u00e9 vers plus de science et d\u2019exp\u00e9rimentation syst\u00e9matique document\u00e9e. Les contraintes de d\u00e9veloppement de l\u2019entreprise l\u2019obligent \u00e0 optimiser les processus, limitant l\u2019\u00e9tendue de l\u2019analyse et de la documentation d\u00e8s qu\u2019une solution est trouv\u00e9e.\u00a0 Le foss\u00e9 s\u2019\u00e9largit entre les exigences et la r\u00e9alit\u00e9.<\/p>\n<p>Voil\u00e0 pourquoi nous pr\u00e9sentons ici un guide pratique de r\u00e9daction de la description technique du<strong> <a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/formulaires-publications\/formulaires\/t661.html\" target=\"_blank\" rel=\"noopener noreferrer\">formulaire T661<\/a>.<\/strong><\/p>\n<div class=\"citation-quote\">\u00ab Dans la description technique cu cr\u00e9dit R&amp;D il faut vendre le processus syst\u00e9matique de r\u00e9solution des probl\u00e8mes technologiques \u00bb<\/div>\n<h2>2- L\u2019importance de la description technique<\/h2>\n<p>Le<strong> <a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/formulaires-publications\/formulaires\/t661.html\" target=\"_blank\" rel=\"noopener noreferrer\">formulaire T661<\/a> <\/strong>est prescrit, c\u2019est-\u00e0-dire qu\u2019il est absolument n\u00e9cessaire pour r\u00e9clamer le cr\u00e9dit RS&amp;DE. La description du projet doit \u00eatre pr\u00e9sent\u00e9e dans la parte 2 du formulaire, \u00e0 la section B aux lignes 242, 244 et 246.\u00a0 Le nombres de mots inscrits \u00e0 ces trois lignes ne doivent pas d\u00e9passer 350, 700 et 350 respectivement. Vos r\u00e9ponses doivent donc \u00eatre centr\u00e9es sur les faits techniques et \u00eatre formul\u00e9es dans un langage et un style technique.<\/p>\n<p>Ces textes seront lus par des conseillers en recherche et technologie (CRT) dans le cadre de l\u2019\u00e9valuation pr\u00e9liminaire du risque associ\u00e9 \u00e0 votre dossier. Si le risque est jug\u00e9 suffisant, votre r\u00e9clamation sera s\u00e9lectionn\u00e9e pour une demande d\u2019information suppl\u00e9mentaire et, dans la plupart des cas, pour une rencontre de v\u00e9rification.<\/p>\n<p>On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre, mais une bonne description peut certainement cr\u00e9er une bonne impression aupr\u00e8s du CRT et en minimiser ainsi les v\u00e9rifications et autres impacts n\u00e9gatifs. C\u2019est donc un document tr\u00e8s important qui peut d\u00e9clencher ou vous \u00e9viter une telle <strong><a href=\"https:\/\/rdactionconsultant.com\/services-rsde\/credit-d-impot-innovation\/\" target=\"_blank\" rel=\"noopener noreferrer\">v\u00e9rification<\/a><\/strong>.<\/p>\n<h2>3- Positionnement du projet<\/h2>\n<p>Dans un pr\u00e9c\u00e9dent article, nous avons identifi\u00e9<strong> <a href=\"https:\/\/rdactionconsultant.com\/ecrire-vos-descriptions-rsde-4-erreurs\/\" target=\"_blank\" rel=\"noopener noreferrer\">quatre erreurs fr\u00e9quentes de positionnement<\/a><\/strong> que nous retrouvons dans les descriptions de projets RS&amp;DE. Voyons maintenant comment positionner notre projet de fa\u00e7on \u00e0 maximiser vos chances qu\u2019il soit accept\u00e9.<\/p>\n<h3>3.1 C\u2019est une vente<\/h3>\n<p>On a l\u2019habitude de produire des textes o\u00f9 l\u2019on vend \u00e0 nos clients potentiels les avantages de notre technologie. On peut voir la description de projets comme une autre sorte de vente. Par contre, il y a des diff\u00e9rences importantes\u00a0:<\/p>\n<ul>\n<li>Au lieu de vendre les avantages (r\u00e9sultats) de notre technologie, nous allons vendre notre processus exp\u00e9rimental, le fait que nous avons proc\u00e9d\u00e9 selon la m\u00e9thode scientifique. Les r\u00e9sultats (succ\u00e8s ou \u00e9chec de notre produit) ont peu d\u2019importance.<\/li>\n<li>Au lieu de vendre \u00e0 des clients potentiels, notre public cible est constitu\u00e9 de quelques CRT et leurs gestionnaires \u00e0 l\u2019ARC.<\/li>\n<li>Le succ\u00e8s de notre vente sera mesur\u00e9 en projets accept\u00e9s et en cr\u00e9dits d\u2019imp\u00f4t obtenus et non en ventes nouvelles.<\/li>\n<\/ul>\n<h3>3.2 Vendre un proc\u00e9d\u00e9 exp\u00e9rimental<\/h3>\n<p>Prenons l\u2019analogie de l\u2019automobile. Pour vendre une automobile, le vendeur insiste sur les caract\u00e9ristiques du produit, sur ses qualit\u00e9s et sur les sentiments qu\u2019il inspire :<\/p>\n<ul>\n<li>Est belle et jaune,<\/li>\n<li>Elle va vite<\/li>\n<li>Ses si\u00e8ges en cuir sont confortables,<\/li>\n<\/ul>\n<p>Ce qu\u2019il faut pr\u00e9senter dans notre description RS&amp;DE ce ne sont pas les caract\u00e9ristiques de la voiture, mais plut\u00f4t ce que vous avez modifi\u00e9 dans cette voiture. Il faut donc :<\/p>\n<ul>\n<li>soulever le capot et expliquer vos objectifs technologiques et les limites des technologies en place en rapport avec l\u2019objectif recherch\u00e9.<\/li>\n<li>expliquer que pour atteindre notre objectif, le progr\u00e8s recherch\u00e9 consiste \u00e0 d\u00e9passer les limites de la technologie existante (et non de simplement la remplacer).<\/li>\n<li>illustrer le processus exp\u00e9rimental syst\u00e9matique suivi et chacune des hypoth\u00e8ses identifi\u00e9es.<\/li>\n<\/ul>\n<h2>4- Comment r\u00e9diger : commentaires g\u00e9n\u00e9raux<\/h2>\n<p>Commen\u00e7ons par quelques commentaires g\u00e9n\u00e9raux sur la fa\u00e7on de r\u00e9diger la description technique d\u2019un projet.<\/p>\n<ul>\n<li><strong><u>D\u00e9taillez votre contenu<\/u><\/strong>. Commencez en couchant tous les d\u00e9tails du projet sur papier. Vous verrez alors l\u2019ensemble de votre processus et cela facilitera votre travail de description et celui du lecteur.<\/li>\n<li><strong><u>D\u00e9coupez le projet RS&amp;DE<\/u><\/strong>. Une fois les d\u00e9tails bien \u00e9tablis, \u00e9ditez strat\u00e9giquement le contenu pour resserrer la description autour des aspects plus pertinents au projet de RS&amp;DE. \u00c9liminez les d\u00e9tails inutiles pour votre argument de RS&amp;DE.<\/li>\n<li><strong><u>Concentrez-vous sur les \u00e9tapes cl\u00e9<\/u><\/strong> et les incertitudes ou activit\u00e9s difficiles afin de pouvoir inclure des mesures quantifiables, des statistiques des conclusions et autres preuves.<\/li>\n<li><strong><u>Communication logique et concise<\/u><\/strong>. La progression des id\u00e9es doit d\u00e9couler doucement entre les sections, permettant au lecteur de passer au travers du document rapidement sans chercher d\u2019autre information.<\/li>\n<li><strong><u>Langage technique<\/u><\/strong>. La description du projet doit \u00eatre dans le langage technique et le style de ceux qui font le travail r\u00e9el ou qui comprennent et sont familiers avec le travail.<\/li>\n<li><strong><u>Pas de \u00ab\u00a0buzzwords\u00a0\u00bb inutiles<\/u><\/strong>. Restreindre d&rsquo;introduire tout jargon, mots \u00e0 la mode ou d&rsquo;autres expressions pseudo techniques ou des abr\u00e9viations. Les d\u00e9tails techniques doivent \u00eatre restrictifs et sp\u00e9cifiques si n\u00e9cessaire pour la simplicit\u00e9 du document. \u00c9vitez au lecteur d&rsquo;\u00eatre pris dans trop de d\u00e9tails, car cela peut le conduire \u00e0 des id\u00e9es fausses sur le travail accompli et les progr\u00e8s recherch\u00e9s.<\/li>\n<li><strong><u>Recherche syst\u00e9matique<\/u><\/strong>. L&rsquo;explication doit se concentrer sur les faits techniques illustrant la nature exp\u00e9rimentale ou analytique des travaux. Il faut montrer une enqu\u00eate ou une recherche syst\u00e9matique par exp\u00e9rimentation ou analyse. Il faut aussi montrer que le but du travail \u00e9tait de r\u00e9aliser un progr\u00e8s dans un domaine de la science ou de la technologie.<\/li>\n<li><strong><u>Conservez les d\u00e9tails<\/u><\/strong>. \u00c9tant donn\u00e9es les limites d\u2019espace pour \u00e9crire, il est intelligent de pr\u00e9parer en m\u00eame temps une documentation (un cartable ou un document de travail), contenant des explications plus d\u00e9taill\u00e9es pr\u00eates \u00e0 l\u2019avance pour une \u00e9ventuelle v\u00e9rification.<\/li>\n<li><strong><u>Continuit\u00e9 entre les projets<\/u><\/strong>. Les projets se terminent rarement en fin d\u2019exercice financier.\n<ol>\n<li>Pour les projets qui se continuent pr\u00e9sentez les projets dans la m\u00eame s\u00e9quence que l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Ceci facilite les r\u00e9f\u00e9rences pour le CRT. De plus, rappelons-nous, le but c\u2019est qu\u2019ils le lisent le plus rapidement possible, r\u00e9duisant ainsi le temps pass\u00e9 sur votre dossier et la probabilit\u00e9 d\u2019avoir d\u2019autres questions.<\/li>\n<li>Pour les projets termin\u00e9s, \u00e9tablissez clairement pourquoi les projets continus des ann\u00e9es ant\u00e9rieures n\u2019ont pas \u00e9t\u00e9 poursuivis ou r\u00e9clam\u00e9s durant l\u2019ann\u00e9e courante.<\/li>\n<\/ol>\n<\/li>\n<li><strong><u>Gardez les choses simples<\/u><\/strong>. Il n\u2019est pas n\u00e9cessaire de d\u00e9tailler individuellement tous les petits projets. On peut combiner des projets, en autant qu\u2019ils aient des technologies similaires (par exemple dans des domaines d\u2019application diff\u00e9rents).<\/li>\n<li><strong><u>Titres technologiques, pas le nom de clients<\/u><\/strong>. Les projets technologiques portent des noms diff\u00e9rents des projets d\u2019affaire. La m\u00eame technologie est parfois utilis\u00e9e dans diff\u00e9rents projets clients. Dans ce cas, le concept int\u00e9grateur d\u2019AXE technologique peut \u00eatre compris par l\u2019ARC.<\/li>\n<li><strong><u>Pas de projets de R&amp;D \u00ab \u00e9ternels\u00a0\u00bb<\/u><\/strong>. Attention aux projets qui durent plus de trois ans. L\u2019ARC cherche \u00e0 couper les projets qu\u2019ils croient sans fin. R\u00e9\u00e9valuez les projets courants pour voir s\u2019il y a de nouveaux angles technologiques \u00e0 pr\u00e9senter. Si non, arr\u00eatez de r\u00e9clamer le projet et partez en de nouveaux sous des noms mieux appropri\u00e9s en relation avec de nouveaux objectifs et incertitudes.<\/li>\n<li><strong><u>Activit\u00e9s de support<\/u><\/strong>. \u00c9vitez de d\u00e9tailler des activit\u00e9s de support \u00e0 vos recherches. Les descriptions de projets sont courtes. Elles ont pour effet de faire le focus comme des lentilles sur diff\u00e9rents aspects du projet. En somme, si\u00a0vous listez TOUTES les activit\u00e9s de support, vous donnez au lecteur l\u2019impression que votre r\u00e9clamation est surtout compos\u00e9e d\u2019activit\u00e9s de support et qu\u2019il y a donc du surplus \u00e0 couper.<\/li>\n<li><strong><u>Reviseur externe<\/u><\/strong>. Se faire r\u00e9viser par quelqu\u2019un de non familier avec le mat\u00e9riel est toujours une bonne id\u00e9e, cela fera ressortir des trous dans les raisonnements et les explications. Parfois le cr\u00e9ateur de la technologie a le nez trop pr\u00e8s du mat\u00e9riel et certaines des \u00e9tapes sont n\u00e9glig\u00e9es ou les liens entre les \u00e9tapes ne sont pas bien expliqu\u00e9s.<\/li>\n<li><strong><u>Impliquez-vous<\/u><\/strong>. Consacrez le temps et l\u2019effort n\u00e9cessaires pour bien pr\u00e9parer ces documents. Aidez l\u2019ARC \u00e0 dire \u00ab oui \u00bb \u00e0 votre R&amp;D. \u00c7a vaut la peine.<\/li>\n<\/ul>\n<p>En conclusion, voil\u00e0\u00a0les commentaires g\u00e9n\u00e9raux sur la r\u00e9daction de vos descriptions de projets RS&amp;DE. Dans de prochains articles, nous vous expliquerons comment r\u00e9diger les sections 242,244 et 246 du<strong> <a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/formulaires-publications\/formulaires\/t661.html\" target=\"_blank\" rel=\"noopener noreferrer\">formulaire T661<\/a>.<\/strong><\/p>\n<p>Et vous, avez-vous des commentaires, suggestions et exp\u00e9riences \u00e0 partager \u00e0 ce sujet ?<\/p>\n<p>Vous avez aim\u00e9 votre lecture ? Dites-le nous. Que devrait-on y ajouter ?<\/p>\n<p>Vous n\u2019avez pas aim\u00e9 votre lecture ? Dites-le nous. Que devrait-on corriger ?<\/p>\n<p>Quels autres sujets vous int\u00e9ressent ?<\/p><\/div>\n<p><!-- .vgblk-rw-wrapper --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour r\u00e9clamer des cr\u00e9dits RS&amp;DE vous devez remplir le formulaire T661. L\u2019ARC fournit plusieurs informations pour faciliter la pr\u00e9paration des dossiers de r\u00e9clamation et pr\u00e9parer ce formulaire\u00a0: Le guide T4088 explique comment remplir ce formulaire ligne par ligne. La politique sur l&rsquo;admissibilit\u00e9 des travaux \u00e0 la RS&amp;DE propose une m\u00e9thodologie pour d\u00e9terminer s\u2019il y a&#8230;<\/p>\n","protected":false},"author":8,"featured_media":1191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[73],"tags":[],"class_list":["post-1599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redaction"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment r\u00e9diger votre description | R&amp;D Action Consultant<\/title>\n<meta name=\"description\" content=\"On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre. En sachant comment r\u00e9diger une description on peut cr\u00e9er une bonne impression aupr\u00e8s du CRT.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment r\u00e9diger votre description | R&amp;D Action Consultant\" \/>\n<meta property=\"og:description\" content=\"On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre. En sachant comment r\u00e9diger une description on peut cr\u00e9er une bonne impression aupr\u00e8s du CRT.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/\" \/>\n<meta property=\"og:site_name\" content=\"R&amp;D Action\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RD-Action-106172664280275\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-27T19:18:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T18:29:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2016\/11\/hands-2069206_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MichelRheault\" \/>\n<meta name=\"twitter:site\" content=\"@MichelRheault\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/\"},\"author\":{\"name\":\"Michel\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/person\\\/74428c00cae6b69bee4b04a0d8637c41\"},\"headline\":\"Comment r\u00e9diger votre description RS&#038;DE\",\"datePublished\":\"2016-09-27T19:18:18+00:00\",\"dateModified\":\"2025-11-27T18:29:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/\"},\"wordCount\":1809,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/hands-2069206_1920.jpg\",\"articleSection\":[\"R\u00e9daction\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/\",\"name\":\"Comment r\u00e9diger votre description | R&D Action Consultant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/hands-2069206_1920.jpg\",\"datePublished\":\"2016-09-27T19:18:18+00:00\",\"dateModified\":\"2025-11-27T18:29:29+00:00\",\"description\":\"On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre. En sachant comment r\u00e9diger une description on peut cr\u00e9er une bonne impression aupr\u00e8s du CRT.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/hands-2069206_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/hands-2069206_1920.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Comment r\u00e9diger votre description RS&DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/comment-rediger-votre-description\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogue\",\"item\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/blogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment r\u00e9diger votre description RS&#038;DE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\",\"name\":\"R&D Action\",\"description\":\"R&amp;D Action Consultant est votre partenaire privil\u00e9gi\u00e9 pour votre cr\u00e9dit d\u2019imp\u00f4t recherche et votre subvention d\u2019entreprise au Qu\u00e9bec. Nos services s\u2019adaptent \u00e0 vos besoins.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#organization\",\"name\":\"R&D Action\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/rd-action-white-logo.png\",\"contentUrl\":\"https:\\\/\\\/rdactionconsultant.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/rd-action-white-logo.png\",\"width\":640,\"height\":172,\"caption\":\"R&D Action\"},\"image\":{\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RD-Action-106172664280275\\\/\",\"https:\\\/\\\/x.com\\\/MichelRheault\",\"https:\\\/\\\/ca.linkedin.com\\\/in\\\/michelrheault-rdaction\",\"https:\\\/\\\/www.instagram.com\\\/r_daction\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rdactionconsultant.com\\\/fr\\\/#\\\/schema\\\/person\\\/74428c00cae6b69bee4b04a0d8637c41\",\"name\":\"Michel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbf63db816d551eeaa1543242eb77b9ba9a3e5b7b7c7a549e5bd2fd65a69d655?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbf63db816d551eeaa1543242eb77b9ba9a3e5b7b7c7a549e5bd2fd65a69d655?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bbf63db816d551eeaa1543242eb77b9ba9a3e5b7b7c7a549e5bd2fd65a69d655?s=96&d=mm&r=g\",\"caption\":\"Michel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment r\u00e9diger votre description | R&D Action Consultant","description":"On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre. En sachant comment r\u00e9diger une description on peut cr\u00e9er une bonne impression aupr\u00e8s du CRT.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment r\u00e9diger votre description | R&D Action Consultant","og_description":"On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre. En sachant comment r\u00e9diger une description on peut cr\u00e9er une bonne impression aupr\u00e8s du CRT.","og_url":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/","og_site_name":"R&amp;D Action","article_publisher":"https:\/\/www.facebook.com\/RD-Action-106172664280275\/","article_published_time":"2016-09-27T19:18:18+00:00","article_modified_time":"2025-11-27T18:29:29+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2016\/11\/hands-2069206_1920.jpg","type":"image\/jpeg"}],"author":"Michel","twitter_card":"summary_large_image","twitter_creator":"@MichelRheault","twitter_site":"@MichelRheault","twitter_misc":{"\u00c9crit par":"Michel","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#article","isPartOf":{"@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/"},"author":{"name":"Michel","@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/person\/74428c00cae6b69bee4b04a0d8637c41"},"headline":"Comment r\u00e9diger votre description RS&#038;DE","datePublished":"2016-09-27T19:18:18+00:00","dateModified":"2025-11-27T18:29:29+00:00","mainEntityOfPage":{"@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/"},"wordCount":1809,"commentCount":0,"publisher":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#organization"},"image":{"@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#primaryimage"},"thumbnailUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2016\/11\/hands-2069206_1920.jpg","articleSection":["R\u00e9daction"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/","url":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/","name":"Comment r\u00e9diger votre description | R&D Action Consultant","isPartOf":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#primaryimage"},"image":{"@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#primaryimage"},"thumbnailUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2016\/11\/hands-2069206_1920.jpg","datePublished":"2016-09-27T19:18:18+00:00","dateModified":"2025-11-27T18:29:29+00:00","description":"On ne peut \u00e9viter une v\u00e9rification de temps \u00e0 autre. En sachant comment r\u00e9diger une description on peut cr\u00e9er une bonne impression aupr\u00e8s du CRT.","breadcrumb":{"@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#primaryimage","url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2016\/11\/hands-2069206_1920.jpg","contentUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2016\/11\/hands-2069206_1920.jpg","width":1024,"height":683,"caption":"Comment r\u00e9diger votre description RS&DE"},{"@type":"BreadcrumbList","@id":"https:\/\/rdactionconsultant.com\/fr\/blogue\/comment-rediger-votre-description\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rdactionconsultant.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blogue","item":"https:\/\/rdactionconsultant.com\/fr\/blogue\/"},{"@type":"ListItem","position":3,"name":"Comment r\u00e9diger votre description RS&#038;DE"}]},{"@type":"WebSite","@id":"https:\/\/rdactionconsultant.com\/fr\/#website","url":"https:\/\/rdactionconsultant.com\/fr\/","name":"R&D Action","description":"R&amp;D Action Consultant est votre partenaire privil\u00e9gi\u00e9 pour votre cr\u00e9dit d\u2019imp\u00f4t recherche et votre subvention d\u2019entreprise au Qu\u00e9bec. Nos services s\u2019adaptent \u00e0 vos besoins.","publisher":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdactionconsultant.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rdactionconsultant.com\/fr\/#organization","name":"R&D Action","url":"https:\/\/rdactionconsultant.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2023\/06\/rd-action-white-logo.png","contentUrl":"https:\/\/rdactionconsultant.com\/wp-content\/uploads\/2023\/06\/rd-action-white-logo.png","width":640,"height":172,"caption":"R&D Action"},"image":{"@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RD-Action-106172664280275\/","https:\/\/x.com\/MichelRheault","https:\/\/ca.linkedin.com\/in\/michelrheault-rdaction","https:\/\/www.instagram.com\/r_daction\/"]},{"@type":"Person","@id":"https:\/\/rdactionconsultant.com\/fr\/#\/schema\/person\/74428c00cae6b69bee4b04a0d8637c41","name":"Michel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bbf63db816d551eeaa1543242eb77b9ba9a3e5b7b7c7a549e5bd2fd65a69d655?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bbf63db816d551eeaa1543242eb77b9ba9a3e5b7b7c7a549e5bd2fd65a69d655?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bbf63db816d551eeaa1543242eb77b9ba9a3e5b7b7c7a549e5bd2fd65a69d655?s=96&d=mm&r=g","caption":"Michel"}}]}},"_links":{"self":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/posts\/1599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/comments?post=1599"}],"version-history":[{"count":1,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/posts\/1599\/revisions"}],"predecessor-version":[{"id":1001379,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/posts\/1599\/revisions\/1001379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/media\/1191"}],"wp:attachment":[{"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/media?parent=1599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/categories?post=1599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rdactionconsultant.com\/fr\/wp-json\/wp\/v2\/tags?post=1599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}